{"id":8,"count":3,"description":"","link":"https:\/\/manga.jadedragononline.com\/muse\/tag\/doctor-who\/","name":"Doctor Who","slug":"doctor-who","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/manga.jadedragononline.com\/muse\/wp-json\/wp\/v2\/tags\/8"}],"collection":[{"href":"https:\/\/manga.jadedragononline.com\/muse\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/manga.jadedragononline.com\/muse\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/manga.jadedragononline.com\/muse\/wp-json\/wp\/v2\/posts?tags=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}